{"id":14075,"date":"2011-06-23T21:31:07","date_gmt":"2011-06-23T19:31:07","guid":{"rendered":"http:\/\/andreas-louis-seyerlein.de\/air\/?p=14075"},"modified":"2024-06-19T23:02:23","modified_gmt":"2024-06-19T21:02:23","slug":"mann-mit-stabchen","status":"publish","type":"post","link":"https:\/\/andreas-louis-seyerlein.de\/air\/mann-mit-stabchen\/","title":{"rendered":"mann mit st\u00e4bchen"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/c\/2.jpg?resize=36%2C80&#038;ssl=1\" alt=\"pic\" width=\"36\" height=\"80\"><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lima-tango-lima\/\">india<\/a><\/span> : 21.02 \u2014 Ich habe einen Mann betrach\u00adtet. Die\u00adser Mann war ganz sicher weit \u00fcber 70 Jah\u00adre alt, trug trotz gro\u00ad\u00dfer Hit\u00adze einen sch\u00e4\u00adbi\u00adgen Win\u00adter\u00adman\u00adtel, Turn\u00adschu\u00adhe, einen zer\u00adschramm\u00adten Ruck\u00adsack vor der Brust, au\u00dfer\u00addem Leder\u00adhand\u00adschu\u00adhe, schmut\u00adzi\u00adge Tei\u00adle, eine Bril\u00adle mit rand\u00adlo\u00adsen, run\u00adden Gl\u00e4\u00adsern, und eben ein fili\u00adgra\u00adnes St\u00e4b\u00adchen, einen Spa\u00adzier\u00adstock genau\u00ader, mit dem er \u00fcber den Boden tas\u00adte\u00adte. Die\u00adser Stock nun war kein gew\u00f6hn\u00adli\u00adcher, viel\u00admehr ein h\u00f6chst merk\u00adw\u00fcr\u00addi\u00adger Stock. Er war von hel\u00adlem Metall und konn\u00adte mit\u00adtels klei\u00adner, im Inne\u00adren des Sto\u00adckes befes\u00adtig\u00adter Elek\u00adtro\u00admo\u00adto\u00adren, ein- und aus\u00adge\u00adfah\u00adren wer\u00adden, eine Art Tele\u00adskop\u00adstock, au\u00dfer\u00addem leicht und blitz\u00adblank, sodass sich die Stadt und der Him\u00admel \u00fcber ihr in ihm spie\u00adgel\u00adten. An der Spit\u00adze des Sto\u00adckes einer\u00adseits war ein rund\u00adli\u00adcher Vor\u00adsatz befes\u00adtigt, am ent\u00adge\u00adgen\u00adge\u00adsetz\u00adten Ende ent\u00adka\u00admen einem Knauf zwei Kabel, die mit H\u00f6r\u00adge\u00adr\u00e4\u00adten ver\u00adbun\u00adden waren, die der alte Mann in sei\u00adnen Ohren trug. Die\u00adse Beob\u00adach\u00adtun\u00adgen, die ich mach\u00adte, als ich die Madi\u00adson Ave\u00adnue s\u00fcd\u00adw\u00e4rts spa\u00adzier\u00adte, f\u00fchr\u00adten zun\u00e4chst zu der Ver\u00admu\u00adtung, der alte Mann belau\u00adsche den Boden, weil ich die Ver\u00adst\u00e4r\u00adkung an der Spit\u00adze sei\u00adnes Sto\u00adckes, zun\u00e4chst f\u00fcr ein Mikro\u00adfon gehal\u00adten habe. Dann aber blieb der alte Mann H\u00f6he 42nd Stra\u00ad\u00dfe nahe der Bord\u00adstein\u00adkan\u00adte ste\u00adhen. Er tas\u00adte\u00adte im Rinn\u00adstein, eine Hand f\u00fchr\u00adte den Stock, die ande\u00adre beweg\u00adte sich in der Tasche sei\u00adnes Man\u00adtels. Indem ich eben\u00adfalls ste\u00adhen\u00adblieb und mich dem alten Mann zuwen\u00adde\u00adte, ver\u00adk\u00fcrz\u00adte sich pl\u00f6tz\u00adlich mit\u00adtels einer geschmei\u00addi\u00adgen Bewe\u00adgung der Stock des Man\u00adnes so weit, dass der alte Mann einen hal\u00adben Dol\u00adlar von sei\u00adnem Ende pfl\u00fc\u00adcken konn\u00adte, ohne in die Knie gehen zu m\u00fcs\u00adsen. \u2014 Ende der Geschich\u00adte. Don\u00adners\u00adtag. Es ist Abend, die Luft k\u00fchl vom Regen. Eine Flie\u00adge tas\u00adtet \u00fcber den Bild\u00adschirm mei\u00adner Schreib\u00adma\u00adschi\u00adne, der Him\u00admel blitzt, die Seen sind voll, das Schilf neigt sich dem Boden zu. \u2014&nbsp;stop<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-14089\" title=\"kindle\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/wp-content\/uploads\/2011\/06\/kindle.jpg?resize=425%2C780&#038;ssl=1\" alt width=\"425\" height=\"780\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>india : 21.02 \u2014 Ich habe einen Mann betrach\u00adtet. Die\u00adser Mann war ganz sicher weit \u00fcber 70 Jah\u00adre alt, trug trotz gro\u00ad\u00dfer Hit\u00adze einen sch\u00e4\u00adbi\u00adgen Win\u00adter\u00adman\u00adtel, Turn\u00adschu\u00adhe, einen zer\u00adschramm\u00adten Ruck\u00adsack vor der Brust, au\u00dfer\u00addem Leder\u00adhand\u00adschu\u00adhe,\u2026 <a class=\"excerpt-more-link\" href=\"https:\/\/andreas-louis-seyerlein.de\/air\/mann-mit-stabchen\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1499,1116],"tags":[1711,1747,1127,1671,38,5346,1656,197,692,886,2341,1166,548,5300,1279,2932,4140,1635,1672,5378,841,1615,5441,81,5252,874,1641,1777,1729,468,1255,525,484,5607,1066,5959,1845,1821,2536,475,1211,1651,109,5010,879,3779,5264,225,223,943,4141,1176,457,5165,931,873,1220,1811,2669,39,1715,3785,872,1652,1105,1762,707,1904,2663,3132,160,2671],"class_list":["post-14075","post","type-post","status-publish","format-standard","hentry","category-schirokko","category-papiergeschichten","tag-abend","tag-alt","tag-art","tag-ast","tag-beobachtung","tag-bewegung","tag-bild","tag-bildschirm","tag-blitz","tag-boden","tag-bordsteinkante","tag-brille","tag-brust","tag-dis","tag-dollar","tag-elektromotor","tag-elle","tag-ende","tag-fest","tag-filigran","tag-fliege","tag-gefahr","tag-geraet","tag-geschichte","tag-geschmeidig","tag-halt","tag-hand","tag-handschuhe","tag-hell","tag-himmel","tag-hitze","tag-ich","tag-india","tag-is","tag-jahre","tag-kant","tag-knie","tag-kuehl","tag-lederhandschuhe","tag-luft","tag-madison-avenue","tag-mann","tag-maschine","tag-merkwuerdig","tag-mich","tag-mikrofon","tag-mikrophon","tag-ohr","tag-ohren","tag-op","tag-os","tag-rand","tag-regen","tag-richtung","tag-rom","tag-rot","tag-rucksack","tag-schicht","tag-schilf","tag-schreibmaschine","tag-schuhe","tag-staebchen","tag-stop","tag-strasse","tag-suedwaerts","tag-teile","tag-turnschuhe","tag-vermutung","tag-vorrichtung","tag-ware","tag-winter","tag-wintermantel"],"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6HQt-3F1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/14075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/comments?post=14075"}],"version-history":[{"count":0,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/14075\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/media?parent=14075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/categories?post=14075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/tags?post=14075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}