{"id":16747,"date":"2012-03-13T06:48:42","date_gmt":"2012-03-13T05:48:42","guid":{"rendered":"http:\/\/andreas-louis-seyerlein.de\/air\/?p=16747"},"modified":"2024-06-26T21:28:33","modified_gmt":"2024-06-26T19:28:33","slug":"minutengeschichten","status":"publish","type":"post","link":"https:\/\/andreas-louis-seyerlein.de\/air\/minutengeschichten\/","title":{"rendered":"minutengeschichten"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"14\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/wp-content\/uploads\/2009\/04\/2.jpg?resize=36%2C80&#038;ssl=1\" alt=\"14\" width=\"36\" height=\"80\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lima-tango-lima\/\">ulys\u00adses<\/a><\/span><\/p>\n<p>~ :&nbsp;louis<br>\nto : dai\u00adsy und vio\u00adlet hilton<br>\nsub\u00adject : MINUTENGESCHICHTEN<\/p>\n<p>Lie\u00adbe Dai\u00adsy, lie\u00adbe Vio\u00adlet! Gr\u00fc\u00df Euch ganz herz\u00adlich! Fr\u00fc\u00adher Mor\u00adgen hier unten bei uns. How are you doing? Ich hat\u00adte, selt\u00adsa\u00adme Sache, in der ver\u00adgan\u00adge\u00adnen Nacht das Gef\u00fchl, irgend\u00adje\u00admand w\u00fcr\u00adde mir, w\u00e4h\u00adrend ich mit mei\u00adnem Blei\u00adstift arbei\u00adte\u00adte, \u00fcber die Schul\u00adter schau\u00aden. Mehr\u00adfach habe ich mich umge\u00adse\u00adhen, auch vor\u00adge\u00adge\u00adben, rein gar nie\u00adman\u00adden bemerkt zu haben, und dann pl\u00f6tz\u00adlich, na, Ihr wisst schon, ich bin mir sicher, Ihr wart in mei\u00adner N\u00e4he gewe\u00adsen, wie noch vor weni\u00adgen Wochen, als ich unter\u00adwegs war in New York, da habe ich Euch leib\u00adhaf\u00adtig gese\u00adhen nachts an Bord der John F. Ken\u00adne\u00addy \u2013 F\u00e4h\u00adre, wie ihr \u00fcbers Salon\u00addeck husch\u00adtet, Gespens\u00adter, w\u00fcr\u00adde man viel\u00adleicht sagen, Geis\u00adter, rei\u00adzen\u00adde Erschei\u00adnun\u00adgen. Sagt, habt Ihr nun gele\u00adsen, was ich notier\u00adte? Jenen klei\u00adnen Text der Minu\u00adten\u00adge\u00adschich\u00adten, den ich so gern mit der Hand wie\u00adder\u00adho\u00adle in schwe\u00adren Zei\u00adten? Ich schick ihn Euch zur Sicher\u00adheit noch ein\u00admal mit, ja, ja, die B\u00fccher\u00admen\u00adschen, das soll\u00adtet Ihr wis\u00adsen, <em>das sind Per\u00adso\u00adnen, die selbst dann noch lesen, wenn sie spa\u00adzie\u00adren gehen. Wenn sie ein\u00admal nicht spa\u00adzie\u00adren gehen, sit\u00adzen sie stu\u00addie\u00adrend auf B\u00e4n\u00adken in Park\u00adland\u00adschaf\u00adten her\u00adum, in Caf\u00e9s oder in einer Unter\u00adgrund\u00adbahn. Dort, aus hei\u00adte\u00adrem Him\u00admel ange\u00adspro\u00adchen, wenn man sich nach ihrem Namen erkun\u00addig\u00adte, w\u00fcr\u00adden sie erschre\u00adcken und sie w\u00fcr\u00adden viel\u00adleicht sagen, ohne den Kopf von der Zei\u00adchen\u00adli\u00adnie zu heben, ich hei\u00ad\u00dfe Anna oder Vic\u00adtor, obwohl sie doch ganz anders hei\u00ad\u00dfen. Wenn man sie frag\u00adte, wo sie sich gera\u00adde befin\u00adden, w\u00fcr\u00adden sie behaup\u00adten, in Petusch\u00adki oder in Brook\u00adlyn oder in Kai\u00adro oder auf einem Amzo\u00adnas\u00adre\u00adgen\u00adwald\u00adfluss. \u2014 Heu\u00adte habe ich mir gedacht, man soll\u00adte f\u00fcr die\u00adse Men\u00adschen eine eige\u00adne Stadt errich\u00adten, eine Metro\u00adpo\u00adle, die allein f\u00fcr lesend durch das Leben rei\u00adsen\u00adde Men\u00adschen gemacht sein wird. Man k\u00f6nn\u00adte nat\u00fcr\u00adlich sagen, wir bau\u00aden kei\u00adne neue Stadt, son\u00addern wir neh\u00admen eine bereits exis\u00adtie\u00adren\u00adde Stadt, die geeig\u00adnet ist, und machen dar\u00adaus eine ganz ande\u00adre Stadt, eine Stadt zun\u00e4chst nur zur Pro\u00adbe. In die\u00adser Stadt lesen\u00adder Men\u00adschen sind Biblio\u00adthe\u00adken zu fin\u00adden wie Blu\u00admen auf einer Wie\u00adse. Da sind also gro\u00ad\u00dfe Biblio\u00adthe\u00adken, und etwas klei\u00adne\u00adre, die haben die Gr\u00f6\u00ad\u00dfe eines Kiosks und sind ge\u00f6ff\u00adnet bei Tag und bei Nacht. Man k\u00f6nn\u00adte dort sehr kost\u00adba\u00adre B\u00fccher ent\u00adlei\u00adhen, sagen wir, f\u00fcr eine Stun\u00adde oder zwei. Dann macht man sich auf den Weg durch die Stadt. W\u00e4h\u00adrend man geht, wird gele\u00adsen. Das ist sehr gesund in die\u00adser Art so in Bewe\u00adgung. Auf alle Stra\u00ad\u00dfen, die man pas\u00adsie\u00adren wird, sind Lini\u00aden auf\u00adge\u00adtra\u00adgen, Stre\u00adcken, die lesen\u00adde Men\u00adschen durch die Stadt gelei\u00adten. Da sind also die gel\u00adben Krei\u00adse der Stun\u00adden- und da sind die roten Lini\u00aden der Minu\u00adten\u00adge\u00adschich\u00adten. Blau sind die Stre\u00adcken m\u00e4ch\u00adti\u00adger B\u00fccher, die schwer sind von feins\u00adten Papie\u00adren. Sie f\u00fch\u00adren weit aufs Land hin\u00adaus bis in die W\u00e4l\u00adder, wo man unge\u00adst\u00f6rt auf sehr beque\u00admen Pini\u00aden\u00adb\u00e4u\u00admen sit\u00adzen und schla\u00adfen kann. In die\u00adser Stadt lesen\u00adder Men\u00adschen haben Auto\u00admo\u00adbi\u00adle, sobald ein lesen\u00adder Mensch sich n\u00e4hert, den Vor\u00adtritt zu geben, und alles ist sehr sch\u00f6n zau\u00adber\u00adhaft beleuch\u00adtet von einem Licht, das aus dem Boden kommt.<\/em> \u2013 Ahoi! Euer Lou\u00adis \u2014&nbsp;stop<\/p>\n<p><small>gesen\u00addet&nbsp;am<br>\n13.03.2012<br>\n06.05&nbsp;MEZ<br>\n3015 zeichen<\/small><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/?cat=783\"><small>lou\u00adis to dai\u00adsy and violet&nbsp;\u00bb<\/small><\/a><\/span><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4483\" title=\"ping\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/wp-content\/uploads\/2009\/04\/ping.jpg?resize=425%2C25&#038;ssl=1\" alt=\"ping\" width=\"425\" height=\"25\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; ulys\u00adses ~ :&nbsp;lou\u00adis to : dai\u00adsy und vio\u00adlet hil\u00adton sub\u00adject : MINUTENGESCHICHTEN Lie\u00adbe Dai\u00adsy, lie\u00adbe Vio\u00adlet! Gr\u00fc\u00df Euch ganz herz\u00adlich! Fr\u00fc\u00adher Mor\u00adgen hier unten bei uns. How are you doing? Ich hat\u00adte, selt\u00adsa\u00adme\u2026 <a class=\"excerpt-more-link\" href=\"https:\/\/andreas-louis-seyerlein.de\/air\/minutengeschichten\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[783,1501],"tags":[2801,1232,701,1127,5346,1367,1691,1344,886,773,16,2025,2629,1982,153,1663,13625,1264,572,1210,4140,1635,690,5269,1178,835,1650,19,1661,4282,950,1634,81,1716,1641,1698,4870,468,525,5607,1486,1248,1384,2039,878,2028,1267,988,466,86,519,892,4290,876,26,2027,879,106,1669,2594,1266,97,1645,825,708,1124,2562,943,4141,68,2026,1498,5348,765,5807,3311,457,1648,873,1667,1811,169,515,100,5267,890,1649,961,545,872,1652,5530,604,1637,956,1706,951,488,1688,5007,503,880,4281,74,966,1643,28,2024,29],"class_list":["post-16747","post","type-post","status-publish","format-standard","hentry","category-twins-mail","category-zeppelin","tag-ahoi","tag-anna","tag-arbeit","tag-art","tag-bewegung","tag-bibliothek","tag-blau","tag-bleistift","tag-boden","tag-brooklyn","tag-buecher","tag-buechermenschen","tag-cafe","tag-dach","tag-daisy-und-violet-hilton","tag-ecke","tag-eiche","tag-einmal","tag-eis","tag-eisen","tag-elle","tag-ende","tag-erscheinung","tag-etwas","tag-existieren","tag-fahre","tag-finden","tag-fragen","tag-gang","tag-geister","tag-gelb","tag-gerade","tag-geschichte","tag-geschichten","tag-hand","tag-herz","tag-herzlich","tag-himmel","tag-ich","tag-is","tag-iss","tag-john-f-kennedy","tag-kairo","tag-kiosk","tag-kopf","tag-kreise","tag-landschaft","tag-landschaften","tag-leben","tag-licht","tag-liebe","tag-louis","tag-mehrfach","tag-mensch","tag-menschen","tag-metropole","tag-mich","tag-minute","tag-minuten","tag-minutengeschichte","tag-morgen","tag-nacht","tag-nachts","tag-net","tag-new-york","tag-niemand","tag-not","tag-op","tag-os","tag-papier","tag-parklandschaften","tag-pen","tag-person","tag-petuschki","tag-pinie","tag-pinien","tag-regen","tag-reisen","tag-rot","tag-schaft","tag-schicht","tag-schlaf","tag-schlafen","tag-sehen","tag-sicherheit","tag-sitzen","tag-sonde","tag-spazieren","tag-stift","tag-stop","tag-strasse","tag-strecke","tag-stunde","tag-stunden","tag-text","tag-ton","tag-tur","tag-ulysses","tag-unten","tag-unterwegs","tag-victor","tag-viele","tag-wal","tag-wesen","tag-wiese","tag-wissen","tag-zeichen","tag-zeichenlinie","tag-zeit"],"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6HQt-4m7","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/16747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/comments?post=16747"}],"version-history":[{"count":0,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/16747\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/media?parent=16747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/categories?post=16747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/tags?post=16747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}