{"id":1882,"date":"2008-11-05T08:30:00","date_gmt":"2008-11-05T07:30:00","guid":{"rendered":"http:\/\/andreas-louis-seyerlein.de\/air\/?p=1882"},"modified":"2024-05-31T20:40:11","modified_gmt":"2024-05-31T18:40:11","slug":"lichtwellensegel","status":"publish","type":"post","link":"https:\/\/andreas-louis-seyerlein.de\/air\/lichtwellensegel\/","title":{"rendered":"lichtwellensegel"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/c\/4.jpg?resize=36%2C80&#038;ssl=1\" alt=\"pic\" width=\"36\" height=\"80\"><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lima-tango-lima\/\">romeo<\/a><\/span> : In der ver\u00adgan\u00adge\u00adnen Nacht war ich begeis\u00adtert in Chi\u00adca\u00adgo auf dem Bild\u00adschirm. Ich hat\u00adte des\u00adhalb kei\u00adne Zeit, einen Text zu schrei\u00adben oder \u00fcber einen Text nach\u00adzu\u00adden\u00adken. Will nun statt\u00addes\u00adsen ein klei\u00adnes St\u00fcck zitie\u00adren, das ich im Okto\u00adber des ver\u00adgan\u00adge\u00adnen Jah\u00adres bereits notier\u00adte, als ich sehr gl\u00fcck\u00adlich gewe\u00adsen war. Fol\u00adgen\u00addes: <em>Man stel\u00adle sich ein\u00admal ein Zim\u00admer vor, ein freund\u00adli\u00adches, hel\u00adles Zim\u00admer von aller\u00adfeins\u00adter Qual\u00adlen\u00adhaut, von Was\u00adser, von Salz, von Licht. Man k\u00f6nn\u00adte die\u00adses Zim\u00admer, und alles, was sich im Zim\u00admer befin\u00addet, das Qual\u00adlen\u00adbett, die Qual\u00adlen\u00aduhr, und all die Qual\u00adlen\u00adb\u00fc\u00adcher und auch die Schreib\u00adma\u00adschi\u00adnen von Qual\u00adlen\u00adhaut, trock\u00adnen und fal\u00adten und sich 10 Gramm schwer in die Hosen\u00adta\u00adsche ste\u00adcken. Und dann geht man mit dem Zim\u00admer durch die Stadt spa\u00adzie\u00adren. Oder man geht kurz mal um die Ecke und setzt sich in ein Kaf\u00adfee\u00adhaus und war\u00adtet. Man sitzt also ganz still und zufrie\u00adden unter einer Ven\u00adti\u00adla\u00adtor\u00adma\u00adschi\u00adne an einem Tisch, trinkt einen Becher Kakao und l\u00e4chelt und ist gedul\u00addig und sehr zufrie\u00adden, weil nie\u00admand wei\u00df, dass man ein Zim\u00admer in der Hosen\u00adta\u00adsche mit sich f\u00fchrt, ein Zim\u00admer, das man jeder\u00adzeit aus\u00adpa\u00adcken und mit etwas Was\u00adser, Salz und Licht, zur sch\u00f6ns\u00adten Ent\u00adfal\u00adtung brin\u00adgen k\u00f6nn\u00adte. \u2013 Null Uhr acht: Haben wir noch alle Tas\u00adsen im Schrank? \u2014&nbsp;stop<\/em><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/picon\/meduse.jpg?resize=425%2C550&#038;ssl=1\" alt=\"ping\" width=\"425\" height=\"550\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>romeo : In der ver\u00adgan\u00adge\u00adnen Nacht war ich begeis\u00adtert in Chi\u00adca\u00adgo auf dem Bild\u00adschirm. Ich hat\u00adte des\u00adhalb kei\u00adne Zeit, einen Text zu schrei\u00adben oder \u00fcber einen Text nach\u00adzu\u00adden\u00adken. Will nun statt\u00addes\u00adsen ein klei\u00adnes St\u00fcck zitie\u00adren,\u2026 <a class=\"excerpt-more-link\" href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lichtwellensegel\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1115,1501],"tags":[1185,1747,1127,1709,1656,197,16,2968,70,1663,1264,572,4140,1635,5556,946,5269,1541,934,1209,1146,1661,4282,518,1458,944,1729,955,525,5607,1066,4287,1437,676,2038,466,4186,86,109,97,1124,2562,477,685,943,4141,4230,2037,3258,931,486,45,39,961,1152,872,604,971,956,35,107,3148,3135,947,74,29,1653],"class_list":["post-1882","post","type-post","status-publish","format-standard","hentry","category-quallenzimmer","category-zeppelin","tag-affe","tag-alt","tag-art","tag-bett","tag-bild","tag-bildschirm","tag-buecher","tag-chicago","tag-denken","tag-ecke","tag-einmal","tag-eis","tag-elle","tag-ende","tag-entfaltung","tag-essen","tag-etwas","tag-falten","tag-folgen","tag-freund","tag-frieden","tag-gang","tag-geister","tag-glueck","tag-gramm","tag-haut","tag-hell","tag-hosentasche","tag-ich","tag-is","tag-jahre","tag-jederzeit","tag-kaffee","tag-kaffeehaus","tag-kakao","tag-leben","tag-lens","tag-licht","tag-maschine","tag-nacht","tag-niemand","tag-not","tag-null","tag-oktober","tag-op","tag-os","tag-qualle","tag-quallenhaut","tag-quallenuhr","tag-rom","tag-romeo","tag-schreiben","tag-schreibmaschine","tag-spazieren","tag-still","tag-stop","tag-stunde","tag-tasse","tag-text","tag-traeume","tag-uhr","tag-ventil","tag-ventilator","tag-wasser","tag-wesen","tag-zeit","tag-zimmer"],"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6HQt-um","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/1882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/comments?post=1882"}],"version-history":[{"count":0,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/1882\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/media?parent=1882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/categories?post=1882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/tags?post=1882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}