{"id":23464,"date":"2014-03-25T06:42:28","date_gmt":"2014-03-25T05:42:28","guid":{"rendered":"http:\/\/andreas-louis-seyerlein.de\/air\/?p=23464"},"modified":"2024-07-11T22:11:32","modified_gmt":"2024-07-11T20:11:32","slug":"terminal-nachts","status":"publish","type":"post","link":"https:\/\/andreas-louis-seyerlein.de\/air\/terminal-nachts\/","title":{"rendered":"terminal nachts"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/c\/0.jpg?resize=36%2C80&#038;ssl=1\" alt=\"pic\" width=\"36\" height=\"80\"><\/p>\n<p><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lima-tango-lima\/\">tan\u00adgo<\/a> : 2.28 \u2014 Ges\u00adtern beob\u00adach\u00adte\u00adte ich einen Mann, wie er in einem Buch las. Er sa\u00df nahe einem Caf\u00e9 im Flug\u00adha\u00adfen\u00adter\u00admi\u00adnal 1 auf sei\u00adnem Kof\u00adfer, lehn\u00adte mit dem R\u00fccken an einer Wand, bei\u00adde F\u00fc\u00dfe fest auf dem Boden. Au\u00dfer\u00addem trug er einen breit\u00adkrem\u00adpi\u00adgen Hut von brau\u00adner Far\u00adbe auf dem Kopf und ein blau\u00ades Hemd, wel\u00adches der\u00adart leuch\u00adte\u00adte, dass mei\u00adne Augen bald schmerz\u00adten. Aber im Grun\u00adde war ich auf den Mann nicht wegen sei\u00adner \u00e4u\u00dfe\u00adren Erschei\u00adnung auf\u00admerk\u00adsam gewor\u00adden, es war die Metho\u00adde, wie er die Erz\u00e4h\u00adlung The Pri\u00adce of Salt von Patri\u00adcia High\u00ads\u00admith stu\u00addier\u00adte. Ehe er n\u00e4m\u00adlich eine neue Sei\u00adte des Buches zu lesen begann, riss er die\u00adse n\u00e4chs\u00adte zu lesen\u00adde Sei\u00adte aus dem K\u00f6r\u00adper des Buches her\u00adaus, f\u00fchr\u00adte sie nahe an sei\u00adne Augen her\u00adan, las, dreh\u00adte die Sei\u00adte her\u00adum, las wei\u00adter, um kurz dar\u00adauf die gele\u00adse\u00adne Sei\u00adte in die Tasche sei\u00adnes Jacketts zu stop\u00adfen. Das Jackett beul\u00adte bereits auf bei\u00adden Sei\u00adten deut\u00adlich, weil das Buch bis zur H\u00e4lf\u00adte gele\u00adsen wor\u00adden war. Genau genom\u00admen zer\u00adleg\u00adte der Mann das Buch, das er las, in sei\u00adne papie\u00adre\u00adnen Ein\u00adzel\u00adtei\u00adle, das Buch ver\u00adschwand sozu\u00adsa\u00adgen unter sei\u00adnen H\u00e4n\u00adden, das waren \u00fcbri\u00adgens win\u00adzi\u00adge H\u00e4n\u00adde, die H\u00e4n\u00adde eines Kin\u00addes. Nat\u00fcr\u00adlich kann ich an die\u00adser Stel\u00adle kei\u00adne Aus\u00adsa\u00adge dar\u00ad\u00fcber machen, ob der Mann mit jedem der B\u00fccher sei\u00adnes Lebens so gehan\u00addelt hat\u00adte. Wann war es gewe\u00adsen, als er die ers\u00adte Sei\u00adte aus einem Buch ent\u00adnahm? Und war\u00adum? Ich woll\u00adte den Mann fra\u00adgen, aber irgend\u00adet\u00adwas hin\u00adder\u00adte mich dar\u00adan, zu ihm zu gehen. Um kurz nach zwei Uhr stand ich auf und ging nach Hau\u00adse. \u2014&nbsp;stop<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/ping.jpg?w=660&#038;ssl=1\" alt=\"ping\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>tan\u00adgo : 2.28 \u2014 Ges\u00adtern beob\u00adach\u00adte\u00adte ich einen Mann, wie er in einem Buch las. Er sa\u00df nahe einem Caf\u00e9 im Flug\u00adha\u00adfen\u00adter\u00admi\u00adnal 1 auf sei\u00adnem Kof\u00adfer, lehn\u00adte mit dem R\u00fccken an einer Wand, bei\u00adde F\u00fc\u00dfe\u2026 <a class=\"excerpt-more-link\" href=\"https:\/\/andreas-louis-seyerlein.de\/air\/terminal-nachts\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1499,1116],"tags":[1747,1127,1655,99,1691,886,1831,15,16,2629,5644,1628,4140,1635,1441,5875,690,82,5269,1710,1672,1139,1121,650,19,177,84,3257,1641,439,614,525,5607,1486,574,878,1697,466,1651,666,879,2805,97,1645,5158,943,68,59,1692,1642,969,5344,872,1985,492,1762,1138,951,107,1694,3132,74],"class_list":["post-23464","post","type-post","status-publish","format-standard","hentry","category-schirokko","category-papiergeschichten","tag-alt","tag-art","tag-auge","tag-augen","tag-blau","tag-boden","tag-braun","tag-buch","tag-buecher","tag-cafe","tag-einzelteil","tag-einzelteile","tag-elle","tag-ende","tag-ente","tag-erle","tag-erscheinung","tag-erzaehlung","tag-etwas","tag-farbe","tag-fest","tag-flughafen","tag-flughafenterminal","tag-frage","tag-fragen","tag-genom","tag-geste","tag-gin","tag-hand","tag-himalaya","tag-hut","tag-ich","tag-is","tag-iss","tag-kind","tag-kopf","tag-koerper","tag-leben","tag-mann","tag-methode","tag-mich","tag-mpi","tag-nacht","tag-nachts","tag-naemlich","tag-op","tag-papier","tag-patricia-highsmith","tag-ruecken","tag-seite","tag-seiten","tag-sozusagen","tag-stop","tag-tang","tag-tango","tag-teile","tag-terminal","tag-tur","tag-uhr","tag-wand","tag-ware","tag-wesen"],"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6HQt-66s","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/23464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/comments?post=23464"}],"version-history":[{"count":0,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/23464\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/media?parent=23464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/categories?post=23464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/tags?post=23464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}