{"id":24606,"date":"2014-09-05T01:58:39","date_gmt":"2014-09-04T23:58:39","guid":{"rendered":"http:\/\/andreas-louis-seyerlein.de\/air\/?p=24606"},"modified":"2024-07-12T22:34:23","modified_gmt":"2024-07-12T20:34:23","slug":"krim-lichtbild-2","status":"publish","type":"post","link":"https:\/\/andreas-louis-seyerlein.de\/air\/krim-lichtbild-2\/","title":{"rendered":"krim : lichtbild No&nbsp;2"},"content":{"rendered":"<p><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lima-tango-lima\/\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4468\" title=\"5\" src=\"https:\/\/andreas-louis-seyerlein.de\/air\/g\/c\/1.jpg\" alt=\"9\" width=\"36\" height=\"80\"><\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lima-tango-lima\/\">ulys\u00adses<\/a><\/span> : 6.55 \u2014 Asso\u00adcia\u00adted Press ver\u00ad\u00f6f\u00adfent\u00adlichte vor eini\u00adgen Mona\u00adten eine bemer\u00adkens\u00adwer\u00adte Foto\u00adgra\u00adfie. Men\u00adschen sind zu sehen, die an der Kas\u00adse eines Ladens dar\u00adauf war\u00adten, bedient zu wer\u00adden, oder Waren, die sie in Plas\u00adtik\u00adbeu\u00adteln mit sich f\u00fch\u00adren, bezah\u00adlen zu d\u00fcr\u00adfen. Es han\u00addelt sich bei die\u00adsem Laden offen\u00adsicht\u00adlich um ein Lebens\u00admit\u00adtel\u00adge\u00adsch\u00e4ft, das von k\u00fcnst\u00adli\u00adchem Licht hell aus\u00adge\u00adleuch\u00adtet wird. Im Hin\u00adter\u00adgrund, rech\u00adter Hand, sind Rega\u00adle zu erken\u00adnen, in wel\u00adchen sich Sekt\u2013 und Wein\u00adfla\u00adschen anein\u00adan\u00adder\u00adrei\u00adhen, gleich dar\u00adun\u00adter eine Tief\u00adk\u00fchl\u00adtruhe in der sich Spei\u00adse\u00adeis befin\u00adden k\u00f6nn\u00adte, und lin\u00adker Hand, an der Wand hin\u00adter der Kas\u00adse, wei\u00adtere Rega\u00adle, Zeit\u00adschrif\u00adten, Spi\u00adri\u00adtuo\u00adsen, Scho\u00adko\u00adlade, Bon\u00adbon\u00adt\u00fc\u00adten. Es ist alles sch\u00f6n bunt, der Laden k\u00f6nn\u00adte sich, wenn man bereit ist, das ein oder ande\u00adre erkenn\u00adbare kyril\u00adli\u00adsche Schrift\u00adzei\u00adchen zu \u00fcber\u00adse\u00adhen, in einem Vor\u00adort der Stadt Paris befin\u00adden oder irgend\u00adwo in einem St\u00e4dt\u00adchen im Nor\u00adden Schwe\u00addens, nahe der Stadt Rom oder im Zen\u00adtrum Lis\u00adsa\u00adbons. Es ist Abend, ver\u00admut\u00adlich oder Nacht, eine k\u00fch\u00adle Nacht, weil die Frau, die vor der Kas\u00adse war\u00adtet, einen Ano\u00adrak tr\u00e4gt von hell\u00adblauer Far\u00adbe und fei\u00adne dunk\u00adle Hosen, ihre Schu\u00adhe sind nicht zu erken\u00adnen, aber die Schu\u00adhe der M\u00e4n\u00adner, es sind vier Per\u00adso\u00adnen, ver\u00admut\u00adlich mitt\u00adle\u00adren Alters. Sie tra\u00adgen schwar\u00adze, geschmei\u00addig wir\u00adkende Mili\u00adt\u00e4r\u00adstie\u00adfel, au\u00dfer\u00addem Uni\u00adfor\u00admen von dun\u00adkel\u00adgr\u00fc\u00adner Far\u00adbe, run\u00adde Schutz\u00adhelme, \u00fcber wel\u00adchen sich eben\u00adso dun\u00adkel\u00adgr\u00fcne Tarn\u00adstoffe span\u00adnen, wei\u00adter\u00adhin Wes\u00adten mit aller\u00adlei Kampf\u00adwerk\u00adzeu\u00adgen, der ein oder ande\u00adre der M\u00e4n\u00adner je eine Sturm\u00adwind\u00adbrille, Knie\u00adsch\u00fct\u00adzer, Hand\u00adschuhe. Die Gesich\u00adter der M\u00e4n\u00adner sind der\u00adart ver\u00admummt, dass nur ihre Augen wahr\u00adzu\u00adneh\u00admen sind, nicht ihre Nasen, nicht ihre Wan\u00adgen, nicht ihre M\u00fcn\u00adder. Sie tra\u00adgen kei\u00adne Hoheits\u00adzei\u00adchen, aber sie wir\u00adken kampf\u00adbe\u00adreit. Einer der M\u00e4n\u00adner schaut miss\u00adtrau\u00adisch zur Kame\u00adra hin, die ihn ins Visier genom\u00admen hat, ein Blick kurz vor Gewalt\u00adt\u00e4\u00adtig\u00adkeit. Jeder Blick hin\u00adter eine Mas\u00adke her\u00advor ist ein selt\u00adsa\u00admer Blick. Einer ande\u00adrer der M\u00e4n\u00adner h\u00e4lt sei\u00adnen Geld\u00adbeu\u00adtel ge\u00f6ff\u00adnet. Die M\u00e4n\u00adner wir\u00adken alle so, als h\u00e4t\u00adten sie sich gera\u00adde von einem Kriegs\u00adge\u00adsche\u00adhen ent\u00adfernt oder nur eine Pau\u00adse ein\u00adge\u00adlegt, ehe es wei\u00adter gehen kann jen\u00adseits die\u00adses Bil\u00addes, das Erstau\u00adnen oder k\u00fch\u00adle Furcht aus\u00adzu\u00adl\u00f6\u00adsen ver\u00admag. Ich stel\u00adle mir vor, ihre Sturm\u00adge\u00adwehre lehn\u00adten vor dem Laden an einer Wand. Und wenn wir gleich her\u00adaus\u00adtre\u00adten an die fri\u00adsche Luft, wenn wir den Blick zum Him\u00admel heben, w\u00fcr\u00adden wir die Ster\u00adne \u00fcber Sim\u00adfe\u00adro\u00adpol erken\u00adnen, oder \u00fcber Jal\u00adta, Luhansk, Mariu\u00adpol. \u2014 stop \/ <small>kof\u00adfer\u00adtest : updated \u2014 ich habe die\u00adse auf\u00adnah\u00adme mit eige\u00adnen augen gesehen.<\/small><br>\n<img decoding=\"async\" src=\"https:\/\/andreas-louis-seyerlein.de\/air\/g\/ping.jpg\" alt=\"ping\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ulys\u00adses : 6.55 \u2014 Asso\u00adcia\u00adted Press ver\u00ad\u00f6f\u00adfent\u00adlichte vor eini\u00adgen Mona\u00adten eine bemer\u00adkens\u00adwer\u00adte Foto\u00adgra\u00adfie. Men\u00adschen sind zu sehen, die an der Kas\u00adse eines Ladens dar\u00adauf war\u00adten, bedient zu wer\u00adden, oder Waren, die sie in Plas\u00adtik\u00adbeu\u00adteln mit\u2026 <a class=\"excerpt-more-link\" href=\"https:\/\/andreas-louis-seyerlein.de\/air\/krim-lichtbild-2\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1114,1116],"tags":[1711,1747,1127,3669,5345,1655,99,4298,1656,1691,958,1166,970,13625,572,4140,1635,1710,1650,18,1666,177,1634,5126,1641,944,1729,468,614,525,5607,1486,3942,1845,178,1144,1821,466,86,3775,491,475,1199,13578,1673,97,1742,825,5061,943,4141,118,2550,5348,931,55,1715,1699,100,1197,3899,3783,872,1675,488,983,4281,1694,3132,552,1198,28,29],"class_list":["post-24606","post","type-post","status-publish","format-standard","hentry","category-lichtbilder","category-papiergeschichten","tag-abend","tag-alt","tag-art","tag-associated-press","tag-aufnahme","tag-auge","tag-augen","tag-bemerkenswert","tag-bild","tag-blau","tag-blick","tag-brille","tag-bunt","tag-eiche","tag-eis","tag-elle","tag-ende","tag-farbe","tag-finden","tag-fotografie","tag-frau","tag-genom","tag-gerade","tag-gewalt","tag-hand","tag-haut","tag-hell","tag-himmel","tag-hut","tag-ich","tag-is","tag-iss","tag-kamera","tag-knie","tag-krieg","tag-krim","tag-kuehl","tag-leben","tag-licht","tag-lichtbild","tag-lima","tag-luft","tag-luhansk","tag-mariupol","tag-maske","tag-nacht","tag-nase","tag-net","tag-offensichtlich","tag-op","tag-os","tag-paris","tag-pause","tag-person","tag-rom","tag-schrift","tag-schuhe","tag-schwarz","tag-sehen","tag-simferopol","tag-speiseeis","tag-sterne","tag-stop","tag-tief","tag-ulysses","tag-update","tag-wal","tag-wand","tag-ware","tag-werk","tag-yalta","tag-zeichen","tag-zeit"],"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6HQt-6oS","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/24606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/comments?post=24606"}],"version-history":[{"count":0,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/24606\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/media?parent=24606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/categories?post=24606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/tags?post=24606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}