{"id":301,"date":"2008-05-02T00:25:45","date_gmt":"2008-05-01T22:25:45","guid":{"rendered":"http:\/\/andreas-louis-seyerlein.de\/air\/?p=301"},"modified":"2024-06-04T17:40:55","modified_gmt":"2024-06-04T15:40:55","slug":"bagdad","status":"publish","type":"post","link":"https:\/\/andreas-louis-seyerlein.de\/air\/bagdad\/","title":{"rendered":"bagdad"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/c\/1.jpg?resize=36%2C80&#038;ssl=1\" alt=\"pic\" width=\"36\" height=\"80\"><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lima-tango-lima\/\">nord\u00adpol<\/a><\/span> : 0.05 \u2014 In Bag\u00addad spricht ein Repor\u00adter vor einer Fern\u00adseh\u00adka\u00adme\u00adra. Men\u00adschen, Pas\u00adsan\u00adten, schau\u00aden ihm \u00fcber die Schul\u00adter, sie machen Vic\u00adto\u00adry\u00adhand\u00adzei\u00adchen in Rich\u00adtung der Kame\u00adra und lachen. Im Hin\u00adter\u00adgrund kreuzt ein Crui\u00adse-Mis\u00adsile eine Stra\u00ad\u00dfe. Der Flug\u00adk\u00f6r\u00adper kommt von rechts und fliegt nach links, er fliegt genau in Ampel\u00adh\u00f6\u00adhe und gera\u00adde so schnell, dass er nicht zu Boden f\u00e4llt. Er fliegt in einer Art und Wei\u00adse, als w\u00fcr\u00adde er sich an Ver\u00adkehrs\u00adre\u00adgeln hal\u00adten. Kur\u00adze Zeit sp\u00e4\u00adter eine Deto\u00adna\u00adti\u00adon, kaum h\u00f6r\u00adbar, aber sicht\u00adbar, eine Ersch\u00fct\u00adte\u00adrung des Bodens, eine Ersch\u00fct\u00adte\u00adrung der Luft, eine Ersch\u00fct\u00adte\u00adrung, die auf den K\u00f6r\u00adper des Kame\u00adra\u00adman\u00adnes ein\u00adwirkt, die sich durch den K\u00f6r\u00adper des Kame\u00adra\u00adman\u00adnes fort\u00adsetzt bis zur Kame\u00adra hin und die Sta\u00adbi\u00adli\u00adt\u00e4t des Bil\u00addes beein\u00adflusst. Auch Hori\u00adzont und Him\u00admel sind ersch\u00fct\u00adtert, wie die Men\u00adschen und ihre Vic\u00adto\u00adry\u00adhandzei\u00adchen. stop. W\u00fcr\u00adden SIE eine 500-Pfund-Bom\u00ad\u00adbe nach einem Men\u00adschen wer\u00adfen? \u2014&nbsp;stop<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/ping.jpg?w=660&#038;ssl=1\" alt=\"ping\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>nord\u00adpol : 0.05 \u2014 In Bag\u00addad spricht ein Repor\u00adter vor einer Fern\u00adseh\u00adka\u00adme\u00adra. Men\u00adschen, Pas\u00adsan\u00adten, schau\u00aden ihm \u00fcber die Schul\u00adter, sie machen Vic\u00adto\u00adry\u00adhand\u00adzei\u00adchen in Rich\u00adtung der Kame\u00adra und lachen. Im Hin\u00adter\u00adgrund kreuzt ein Crui\u00ad\u00adse-Mis\u00ad\u00adsi\u00adle eine Stra\u00ad\u00dfe.\u2026 <a class=\"excerpt-more-link\" href=\"https:\/\/andreas-louis-seyerlein.de\/air\/bagdad\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1499],"tags":[1747,2568,1127,1141,179,1656,886,684,5194,13625,572,5883,67,3635,1634,874,1641,3958,468,525,5607,1486,3942,5191,1697,1644,475,1651,876,26,724,943,2336,2442,1695,4440,5165,100,5330,872,1652,1706,503,1122,28,29],"class_list":["post-301","post","type-post","status-publish","format-standard","hentry","category-schirokko","tag-alt","tag-ampel","tag-art","tag-art-und-weise","tag-bagdad","tag-bild","tag-boden","tag-bombe","tag-detonation","tag-eiche","tag-eis","tag-erschuetterung","tag-fernsehen","tag-flugkoerper","tag-gerade","tag-halt","tag-hand","tag-handzeichen","tag-himmel","tag-ich","tag-is","tag-iss","tag-kamera","tag-kameramann","tag-koerper","tag-links","tag-luft","tag-mann","tag-mensch","tag-menschen","tag-nordpol","tag-op","tag-passanten","tag-pfund","tag-rechts","tag-report","tag-richtung","tag-sehen","tag-sichtbar","tag-stop","tag-strasse","tag-ton","tag-victor","tag-weise","tag-zeichen","tag-zeit"],"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s6HQt-bagdad","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/comments?post=301"}],"version-history":[{"count":0,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/301\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/media?parent=301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/categories?post=301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/tags?post=301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}