{"id":34594,"date":"2018-12-11T19:04:23","date_gmt":"2018-12-11T18:04:23","guid":{"rendered":"https:\/\/andreas-louis-seyerlein.de\/air\/?p=34594"},"modified":"2024-07-26T13:52:07","modified_gmt":"2024-07-26T11:52:07","slug":"faltergeschichte","status":"publish","type":"post","link":"https:\/\/andreas-louis-seyerlein.de\/air\/faltergeschichte\/","title":{"rendered":"faltergeschichte"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/c\/0.jpg?resize=36%2C80&#038;ssl=1\" alt=\"pic\" width=\"36\" height=\"80\"><\/p>\n<p align=\"justify\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/andreas-louis-seyerlein.de\/air\/lima-tango-lima\/\">sier\u00adra<\/a><\/span> : 0.55 \u2014 Ein Nacht\u00adfal\u00adter segel\u00adte durch mein Arbeits\u00adzim\u00admer, als sei er eine Erin\u00adne\u00adrung. Das Tier war so m\u00fcde und so schwach, dass es sich der Luft anver\u00adtrau\u00adte. Kurz dar\u00adauf sa\u00df der Fal\u00adter auf dem Boden und ich hob ihn auf und setz\u00adte ihn behut\u00adsam an eine Wand. \u2014 Es ist jetzt bald 1 Stun\u00adde nach Mit\u00adter\u00adnacht. Ein paar Dioden\u00adlich\u00adter gl\u00fc\u00adhen zu mir her\u00ad\u00fcber. Ich wer\u00adde den Fal\u00adter f\u00fct\u00adtern, wer\u00adde ihn mit\u00adtels Zucker\u00adwas\u00adser \u00fcber den Win\u00adter brin\u00adgen. Er k\u00f6nn\u00adte viel\u00adleicht 250 Jah\u00adre alt, er k\u00f6nn\u00adte ein Lich\u00adten\u00adberg\u00adfal\u00adter sein, der bei mir zu Kr\u00e4f\u00adten kom\u00admen m\u00f6ch\u00adte. \u2014&nbsp;stop<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/ping.jpg?w=660&#038;ssl=1\" alt=\"ping\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>sier\u00adra : 0.55 \u2014 Ein Nacht\u00adfal\u00adter segel\u00adte durch mein Arbeits\u00adzim\u00admer, als sei er eine Erin\u00adne\u00adrung. Das Tier war so m\u00fcde und so schwach, dass es sich der Luft anver\u00adtrau\u00adte. Kurz dar\u00adauf sa\u00df der Fal\u00adter auf\u2026 <a class=\"excerpt-more-link\" href=\"https:\/\/andreas-louis-seyerlein.de\/air\/faltergeschichte\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1499,1116],"tags":[1747,701,3251,1181,886,2042,4140,71,1170,81,5508,614,525,5607,1066,86,3821,475,640,97,859,943,4147,1811,494,872,604,13585,1694,947,160,1653,2918],"class_list":["post-34594","post","type-post","status-publish","format-standard","hentry","category-schirokko","category-papiergeschichten","tag-alt","tag-arbeit","tag-arbeitszimmer","tag-berg","tag-boden","tag-diodenlicht","tag-elle","tag-erinnerung","tag-falter","tag-geschichte","tag-gluehen","tag-hut","tag-ich","tag-is","tag-jahre","tag-licht","tag-lichtenbergfalter","tag-luft","tag-mitternacht","tag-nacht","tag-nachtfalter","tag-op","tag-rinne","tag-schicht","tag-sierra","tag-stop","tag-stunde","tag-vertraut","tag-wand","tag-wasser","tag-winter","tag-zimmer","tag-zuckerwasser"],"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6HQt-8ZY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/34594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/comments?post=34594"}],"version-history":[{"count":0,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/34594\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/media?parent=34594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/categories?post=34594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/tags?post=34594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}