{"id":87,"date":"2007-08-08T06:36:50","date_gmt":"2007-08-08T04:36:50","guid":{"rendered":"http:\/\/andreas-louis-seyerlein.de\/air\/?p=87"},"modified":"2012-12-23T23:18:31","modified_gmt":"2012-12-23T22:18:31","slug":"kartaesernelke","status":"publish","type":"post","link":"https:\/\/andreas-louis-seyerlein.de\/air\/kartaesernelke\/","title":{"rendered":"kart\u00e4usernelke"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/c\/2.jpg?resize=36%2C80&#038;ssl=1\" alt=\"pic\" width=\"36\" height=\"80\"><\/p>\n<p align=\"justify\">2.30 \u2014 Unter dem Begriff <em>Kar\u00adt\u00e4u\u00adser\u00adnel\u00adke <\/em>notiert Wal\u00adter Ben\u00adja\u00admin, dass dem Lie\u00adben\u00adden der gelieb\u00adte Mensch immer ein\u00adsam erschei\u00adne. \u2013 Ein selt\u00adsa\u00admer, ein geheim\u00adnis\u00advol\u00adler Gedan\u00adke. \u2013&nbsp;stop<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/andreas-louis-seyerlein.de\/air\/g\/ping.jpg?w=660&#038;ssl=1\" alt=\"ping\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2.30 \u2014 Unter dem Begriff Kar\u00adt\u00e4u\u00adser\u00adnel\u00adke notiert Wal\u00adter Ben\u00adja\u00admin, dass dem Lie\u00adben\u00adden der gelieb\u00adte Mensch immer ein\u00adsam erschei\u00adne. \u2013 Ein selt\u00adsa\u00admer, ein geheim\u00adnis\u00advol\u00adler Gedan\u00adke. \u2013&nbsp;stop<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1499],"tags":[1747,1127,38,227,15,16,572,1635,71,934,524,4129,5305,525,5607,2052,519,5359,876,26,97,2562,943,5706,872,107,4281,37,947,33],"class_list":["post-87","post","type-post","status-publish","format-standard","hentry","category-schirokko","tag-alt","tag-art","tag-beobachtung","tag-book","tag-buch","tag-buecher","tag-eis","tag-ende","tag-erinnerung","tag-folgen","tag-gedanke","tag-geheimnis","tag-geliebte","tag-ich","tag-is","tag-kartaeusernelke","tag-liebe","tag-liebende","tag-mensch","tag-menschen","tag-nacht","tag-not","tag-op","tag-riff","tag-stop","tag-uhr","tag-wal","tag-walter-benjamin","tag-wasser","tag-wort"],"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6HQt-1p","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":0,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/posts\/87\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/categories?post=87"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreas-louis-seyerlein.de\/air\/wp-json\/wp\/v2\/tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}